{"id":180612,"date":"2024-09-04T13:37:59","date_gmt":"2024-09-04T20:37:59","guid":{"rendered":"https:\/\/foosales.com\/cookie-policy-br\/"},"modified":"2025-03-13T14:54:17","modified_gmt":"2025-03-13T21:54:17","slug":"politica-de-cookies-br","status":"publish","type":"page","link":"https:\/\/www.foosales.com\/pt\/cookie-policy-br\/","title":{"rendered":"Pol\u00edtica de cookies (BR)"},"content":{"rendered":"<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-br\"><p><i>Esta Pol\u00edtica de Cookies foi atualizada pela \u00faltima vez em Outubro 14, 2025 e se aplica a cidad\u00e3os e residentes legais permanentes do Brasil.<\/i><br \/><\/p><h2>1. Introdu\u00e7\u00e3o<\/h2><p>O nosso s\u00edtio, <a href=\"https:\/\/www.foosales.com\/pt\">https:\/\/www.foosales.com\/pt<\/a> (doravante: \"o site\") utiliza cookies e outras tecnologias relacionadas (por conveni\u00eancia todas as tecnologias s\u00e3o referidas como \"cookies\"). Os cookies tamb\u00e9m s\u00e3o inseridos por terceiros que contratamos. No documento abaixo informamos sobre o uso de cookies em nosso site.<\/p><h2>2. O que s\u00e3o cookies?<\/h2><p>Um cookie \u00e9 um arquivo pequeno e simples que \u00e9 enviado junto com p\u00e1ginas deste site e armazenado pelo seu browser no disco r\u00edgido do seu computador ou outro dispositivo. As informa\u00e7\u00f5es armazenadas podem ser enviadas de volta aos nossos servidores ou aos servidores dos terceiros relevantes durante uma visita subsequente.<\/p><h2>3. O que s\u00e3o scripts?<\/h2><p>Um script \u00e9 uma parte de c\u00f3digo de programa usado para fazer o nosso site funcionar de forma adequada e interactiva. Este c\u00f3digo \u00e9 executado no nosso servidor ou no seu dispositivo.<\/p><h2>4. O que \u00e9 um web beacon?<\/h2><p>Um web beacon (ou uma tag pixel) \u00e9 um pequeno e invis\u00edvel texto ou imagem num site que \u00e9 usado para monitorizar o tr\u00e1fego num site. Para fazer isso, v\u00e1rios dados sobre si s\u00e3o armazenados utilizando web beacons.<\/p><h2>5. Biscoitos<\/h2><h3>5.1 Cookies t\u00e9cnicos ou funcionais<\/h3><p>Alguns cookies garantem que certas partes do site funcionem corretamente e que as suas prefer\u00eancias de utilizador permane\u00e7am conhecidas. Ao inserir cookies funcionais, facilitamos a visita ao nosso site. Dessa forma, n\u00e3o precisa inserir repetidamente as mesmas informa\u00e7\u00f5es ao visitar o nosso site e, por exemplo, os itens permanecem no seu carrinho de compras at\u00e9 que tenha conclu\u00eddo a compra. Podemos inserir esses cookies sem o seu consentimento.<\/p><h3>5.2 Cookies anal\u00edticos<\/h3><p>Utilizamos cookies anal\u00edticos para otimizar a experi\u00eancia do site para os nossos utilizadores. Com estes cookies anal\u00edticos, obtemos informa\u00e7\u00f5es sobre o uso do nosso site. Pedimos a sua permiss\u00e3o para inserir cookies anal\u00edticos.<\/p><h3>5.3 Cookies de publicidade<\/h3><p>Neste site, usamos cookies de publicidade, o que nos permite ter uma vis\u00e3o sobre resultados de campanha. Isso acontece com base num perfil que criamos, baseado no seu comportamento em <a href=\"https:\/\/www.foosales.com\/pt\">https:\/\/www.foosales.com\/pt<\/a>. Com esses cookies, como visitante do site, est\u00e1 vinculado a um ID \u00fanico, mas esses cookies n\u00e3o tra\u00e7ar\u00e3o o perfil do seu comportamento e interesses para veicular an\u00fancios personalizados.<\/p><h3>5.4 Cookies de marketing\/rastreio<\/h3><p>Cookies de marketing\/rastreio s\u00e3o cookies ou qualquer outra forma de armazenamento local, usados para criar perfis de utilizador para exibir publicidade ou para rastrear o utilizador neste site ou em v\u00e1rios sites para fins semelhantes de marketing .<\/p><p>Como esses cookies s\u00e3o marcados como cookies de rastreio, pedimos a sua permiss\u00e3o para inseri-los.<\/p><h3>5.5 Rede social<\/h3><p>No nosso site, inclu\u00edmos conte\u00fado do Facebook, LinkedIn e Instagram para promover p\u00e1ginas da web (por exemplo, \"gosto\", \"pin\") ou partilhar (por exemplo, \"twittar\") em redes sociais como Facebook, LinkedIn e Instagram. Este conte\u00fado \u00e9 incorporado com c\u00f3digo derivado do Facebook, LinkedIn e Instagram e coloca cookies. Esse conte\u00fado pode armazenar e processar determinadas informa\u00e7\u00f5es para publicidade personalizada.<\/p><p>Por favor, leia a declara\u00e7\u00e3o de privacidade dessas redes sociais (que podem mudar regularmente) para saber o que elas fazem com os seus dados (pessoais) que processam usando esses cookies. Os dados recuperados s\u00e3o anonimizados tanto quanto poss\u00edvel. O Facebook, o LinkedIn e o Instagram est\u00e3o localizados nos Estados Unidos.<\/p><h2>6. Cookies inseridos<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Adsense<\/h3>\n\t\t<p>Estat\u00edsticas, Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-adsense\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o google-adsense<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-adsense\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-adsense\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Google Adsense para exibir an\u00fancios. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-adsense\/\">Leia mais sobre o Google Adsense<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Adsense Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/auto-draft-23\/\">_gcl_ls<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e acompanhar a intera\u00e7\u00e3o<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/google_adsense_settings\/\">defini\u00e7\u00f5es do google_adsense<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Habilitar entrega de an\u00fancios ou redireccionamento<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Estat\u00edsticas (an\u00f3nimo)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o elemento de servi\u00e7o<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Elementor para a cria\u00e7\u00e3o de conte\u00fado. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Leia mais sobre o Elementor<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas (an\u00f3nimo)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elementar<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar ac\u00e7\u00f5es realizadas no s\u00edtio Web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wistia<\/h3>\n\t\t<p>Estat\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_wistia\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o wistia<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wistia\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wistia\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Wistia para exibi\u00e7\u00e3o de v\u00eddeo. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wistia\/\">Leia mais sobre a Wistia<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/wistia.com\/privacy\">Declara\u00e7\u00e3o de Privacidade da Wistia<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wistia\/wistia-video-progress\/\">wistia-video-progress-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar se o utilizador visualizou conte\u00fado incorporado<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Tema alto<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_themehigh\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o de presta\u00e7\u00e3o de servi\u00e7os - elevado<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_themehigh\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"themehigh\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Themehigh para otimiza\u00e7\u00e3o e estat\u00edsticas de lojinha virtual. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/themehigh\/\">Leia mais sobre Themehigh<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/themehigh\/ast_checkout_form\/\">formul\u00e1rio_de_checkout<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Stripe<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_stripe\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Faixa de consentimento de servi\u00e7o<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_stripe\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"stripe\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Stripe para processamento de pagamentos. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/stripe\/\">Leia mais sobre Stripe<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/stripe.com\/privacy\/\">Stripe Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/stripe\/__stripe_mid\/\">__stripe_mid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Prevenir a fraude<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para a conformidade do servi\u00e7o<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Complianz para gerenciar o consentimento de cookies. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">Leia mais sobre a Complianz<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros. Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">Declara\u00e7\u00e3o de Privacidade da Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_functional\/\">cmplz_functional<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar o ID da pol\u00edtica de cookies aceite<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar se o banner do cookie foi rejeitado<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_user_data\/\">cmplz_user_data<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Ler para determinar qual a faixa de cookies a mostrar<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_saved_services\/\">cmplz_saved_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_id\/\">cmplz_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_saved_categories\/\">cmplz_saved_categories<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de consentimento de cookies<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>An\u00e1lise de pilha<\/h3>\n\t\t<p>Estat\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_heap-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o heap-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_heap-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"heap-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Heap Analytics para estat\u00edsticas de sites. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/heap-analytics\/\">Leia mais sobre Heap Analytics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/heap.io\/privacy\">Heap Analytics Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/heap-analytics\/__trashed-68\/\">_hp2_props.*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">14 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e acompanhar a intera\u00e7\u00e3o<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>AutomatizarWoo<\/h3>\n\t\t<p>Prefer\u00eancias, Funcional<\/p>\n\t\t<label for=\"cmplz_service_automatewoo\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o automatizado<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_automatewoo\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"automatewoo\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o AutomateWoo para automa\u00e7\u00e3o de marketing (marketing por e-mail automatizado). <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/automatewoo\/\">Leia mais sobre o AutomateWoo<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prefer\u00eancias<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/automatewoo\/wp_automatewoo_visitor_\/\">wp_automatewoo_visitor_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">diversos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e acompanhar a intera\u00e7\u00e3o<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/automatewoo\/wp_automatewoo_session_started\/\">wp_automatewoo_session_started<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar a hora da visita<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sourcebuster JS<\/h3>\n\t\t<p>Estat\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_sourcebuster-js\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o para o servi\u00e7o sourcebuster-js<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sourcebuster-js\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sourcebuster-js\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Sourcebuster JS para rastrear visitantes. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/sourcebuster-js\/\">Leia mais sobre o Sourcebuster JS<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_migrations\/\">sbjs_migrations<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar o hist\u00f3rico de utiliza\u00e7\u00e3o do utilizador<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first_add\/\">sbjs_first_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e contar visualiza\u00e7\u00f5es de p\u00e1ginas<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first\/\">sbjs_first<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e acompanhar a intera\u00e7\u00e3o<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_current_add\/\">sbjs_current_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e contar visualiza\u00e7\u00f5es de p\u00e1ginas<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_current\/\">sbjs_current<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes do browser<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_udata\/\">sbjs_udata<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar um ID de sess\u00e3o \u00fanico<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_session\/\">sbjs_session<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 minutos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e contar visualiza\u00e7\u00f5es de p\u00e1ginas<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Brevo<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_brevo\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o brevo<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_brevo\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"brevo\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p> <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/sendinblue\/\">Leia mais sobre a Brevo<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sendinblue\/sib_cuid\/\">sib_cuid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar visitas \u00fanicas<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Marketing, Funcional<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Facebook para exibir publica\u00e7\u00f5es sociais recentes e\/ou bot\u00f5es de partilha social. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\">Leia mais sobre o Facebook<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">Facebook Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e acompanhar as visitas em todos os s\u00edtios Web<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 anos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar \u00faltima visita<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes da conta<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar um ID de in\u00edcio de sess\u00e3o \u00fanico<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Habilitar entrega de an\u00fancios ou redireccionamento<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\">ato<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Manter utilizadores registados<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 anos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer preven\u00e7\u00e3o de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\">c_utilizador<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar um ID de utilizador \u00fanico<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\">sb<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 anos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes do navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes da conta<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 semana<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Determinar a resolu\u00e7\u00e3o de tela<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer preven\u00e7\u00e3o de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\">presen\u00e7a ativa<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e rastrear se a aba do navegador est\u00e1 ativa<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WooCommerce<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_woocommerce\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o woocommerce<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_woocommerce\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"woocommerce\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos WooCommerce para gerenciamento de lojas virtuais. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/woocommerce\/\">Leia mais sobre WooCommerce<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wc_cart_hash_\/\">wc_cart_hash_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar itens adicionados ao carrinho de compras<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wp_woocommerce_session_-2\/\">wp_woocommerce_session_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar ac\u00e7\u00f5es realizadas no s\u00edtio Web<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wc_fragments_\/\">wc_fragmentos_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wc_fragments_\/\">wc_fragmentos_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wc_cart_created\/\">wc_cart_created<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar ac\u00e7\u00f5es realizadas no s\u00edtio Web<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/woocommerce_items_in_cart\/\">woocommerce_items_in_cart<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar itens no carrinho de compras<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/woocommerce_cart_hash\/\">woocommerce_cart_hash<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 dia<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar itens no carrinho de compras<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o de servi\u00e7o wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos WordPress para o desenvolvimento de sites. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Leia mais sobre WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar as prefer\u00eancias do utilizador<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wordfence<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordfence\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o de servi\u00e7o wordfence<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordfence\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordfence\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Wordfence para seguran\u00e7a de sites. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordfence\/\">Leia mais sobre o Wordfence<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.wordfence.com\/privacy-policy\/\">Declara\u00e7\u00e3o de Privacidade da Wordfence<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordfence\/wfwaf-authcookie\/\">wfwaf-authcookie*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 di\u00e2metro<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Verificar se o utilizador realizou login<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Google reCAPTCHA para preven\u00e7\u00e3o de spam. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Leia mais sobre o Google reCAPTCHA<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Filtrar solicita\u00e7\u00f5es de bots<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Filtrar solicita\u00e7\u00f5es de bots<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Filtrar solicita\u00e7\u00f5es de bots<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>LinkedIn<\/h3>\n\t\t<p>Prefer\u00eancias, Funcional, Marketing, Estat\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_linkedin\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para o servi\u00e7o linkedin<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_linkedin\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"linkedin\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o LinkedIn para exibir publica\u00e7\u00f5es sociais recentes e\/ou bot\u00f5es de partilha social. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/linkedin\/\">Leia mais sobre o LinkedIn<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\">LinkedIn Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prefer\u00eancias<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bcookie-2\/\">bcookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes do navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/lidc\/\">lidc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 di\u00e2metro<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer funcionalidade de balanceamento de carga<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li_alerts\/\">li_alertas<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar se uma mensagem foi exibida<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bscookie\/\">bscookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Manter utilizadores registados<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-16\/\">li_gc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de consentimento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-20\/\">sdsc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer funcionalidade de balanceamento de carga<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bizographicsoptout\/\">BizographicsOptOut<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">10 anos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de privacidade<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-19\/\">lms_ads<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e rastrear visitas entre os sites<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/_guid\/\">_guia<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Rastrear a identidade de um visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li-oatml\/\">li-oatml<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 m\u00eas<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Habilitar entrega de an\u00fancios ou redireccionamento<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li_sugr\/\">li_sugr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Rastrear a identidade de um visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/usermatchhistory\/\">UserMatchHistory<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Habilitar entrega de an\u00fancios ou redireccionamento<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-18\/\">lms_analytics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Rastrear a identidade de um visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/analyticssynchistory\/\">AnalyticsSyncHistory<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e rastrear visitas entre os sites<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento de servi\u00e7o youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o YouTube para exibi\u00e7\u00e3o de v\u00eddeo. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Leia mais sobre o YouTube<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Declara\u00e7\u00e3o de Privacidade do YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar dados de localiza\u00e7\u00e3o<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITANTE_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Habilitar entrega de an\u00fancios ou redireccionamento<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar e rastrear intera\u00e7\u00e3o<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">8 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar prefer\u00eancias de utilizador<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o de utiliza\u00e7\u00e3o do servi\u00e7o google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o Google Maps para exibi\u00e7\u00e3o de mapas. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Leia mais sobre o Google Maps<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">API do Google Maps<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">expira imediatamente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Verificar endere\u00e7o IP de utilizador<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>PayPal<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_paypal\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Autoriza\u00e7\u00e3o de servi\u00e7o paypal<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_paypal\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"paypal\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos o PayPal para processamento de pagamentos. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/paypal\/\">Leia mais sobre o PayPal<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.paypal.com\/legalhub\/privacy-full\">Declara\u00e7\u00e3o de Privacidade do PayPal<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/nsid\/\">nsid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">sess\u00e3o<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer preven\u00e7\u00e3o de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/enforce_policy\/\">aplicar_pol\u00edtica<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 ano<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Salvar prefer\u00eancias de privacidade<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/tsrce\/\">tsrce<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/auto-draft-3\/\">ts_c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 anos<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Fornecer preven\u00e7\u00e3o de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/__paypal_storage__\/\">__paypal_storage__<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar detalhes da conta<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Diversos<\/h3>\n\t\t<p>Estat\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_diversos\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimento para servi\u00e7os diversos<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_diversos\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"diversos\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>A partilha de dados est\u00e1 pendente de investiga\u00e7\u00e3o<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalidade pendente de investiga\u00e7\u00e3o<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">persist:hs-beacon-44cc73fb-7636-4206-b115-c7b33823551b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wcpdf_general_settings_accordion_state_2<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-krqb7ckugp<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__wpfvdk<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">persist:hs-beacon-message-44cc73fb-7636-4206-b115-c7b33823551b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-fj7gs031q6<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-s599wdduu1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpr-hash<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-09kolaz9o0<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrer<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wc_cart_hash_d7c6aed80eebee5b1ca703ce04da2bef<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">formbricks-js<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-z1qxl7s2zn<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">li_adsId<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wcpdf_general_settings_accordion_state_0<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">pa<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-frwm2xrksl<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">topicsLastReferenceTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-9m1zg8p5wc<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-803tlui8oi<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">customizerVisitCount<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wcpdf_general_settings_accordion_state_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_wpinitialpermissionstate<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrerTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wcpdf_documents_settings_accordion_state_0<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-7seqacq2ol<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">pa_activado<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wcpdf_documents_settings_accordion_state_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-fj42vucf99<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-j042jylrre<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">storeApiCartData<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mp_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mp_gen_new_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">adobeCleanFontAdded<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_automatewoo_visitor_7c767e78557865a392f6c1461fee2e8b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mtk_src_trk<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">trp_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ga_YZSGRXC11J<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_gcl_au<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_id.2826793817<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-75<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-75<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_gid<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ga_K4WE72Y7ZC<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ga<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ga_THJGR8NY67<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_props_2826793817<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_id_2826793817<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_7c767e78557865a392f6c1461fee2e8b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wfwaf-authcookie-01e6a777a87b0895069ec08f12fac216<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">persist:hs-beacon-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ID da sess\u00e3o<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">email_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_automatewoo_visitor_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_props_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_props.*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_id_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">mailchimp.cart.*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">loja de defini\u00e7\u00f5es<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">m\u00e9tricas de extens\u00e3o de vitais da web<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">userty.core.p.f3de1b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">tracking_email<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">userty_core_p_f3de1b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">p\u00e1gina de sa\u00edda de pontua\u00e7\u00e3o de esfor\u00e7o do cliente<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">faixasQueue<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_hp2_id.*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ga_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_dc_gtm_UA-102092226-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wc_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_dc_gtm_UA-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-173<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_gcl_gs<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_gcl_aw<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_gac_UA-102092226-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-68<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wjecf_free_product_coupons<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">qm-admin-panel<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">qm-painel frontal<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">litespeed-prefer\u00eancia-escura<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_lscache_vary<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estat\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-5wrdzcmj90<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Armazenar se o utilizador viu conte\u00fado incorporado<\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimento<\/h2><p>Quando visitar o nosso site pela primeira vez, mostraremos uma janela com uma explica\u00e7\u00e3o sobre cookies. Assim que clicar em \"Guardar prefer\u00eancias\", autoriza-nos a usar as categorias de cookies e plugins selecionados na janela, conforme descrito nesta Pol\u00edtica de Cookies. Pode desativar o uso de cookies atrav\u00e9s do seu navegador, mas observe que o nosso site pode n\u00e3o funcionar corretamente.<\/p><h3>8.1 Fa\u00e7a a gest\u00e3o das suas configura\u00e7\u00f5es de consentimento<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Carregou a Pol\u00edtica de Cookies sem suporte para javascript. No AMP, pode usar o bot\u00e3o de gest\u00e3o de consentimento na parte inferior da p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>9. Ativa\u00e7\u00e3o\/desativa\u00e7\u00e3o e exclus\u00e3o de cookies<\/h2><p>Pode usar o seu browser para excluir cookies automaticamente ou manualmente. Tamb\u00e9m pode especificar que certos cookies podem n\u00e3o ser inseridos. Outra op\u00e7\u00e3o \u00e9 alterar as configura\u00e7\u00f5es do seu browser para que receba uma mensagem cada vez que um cookie \u00e9 inserido. Para obter mais informa\u00e7\u00f5es sobre essas op\u00e7\u00f5es, consulte as instru\u00e7\u00f5es na sec\u00e7\u00e3o Ajuda do seu browser.<\/p><p>Por favor note que o nosso site pode n\u00e3o funcionar corretamente se todos os cookies forem desativados. Se excluir os cookies do seu navegador, eles ser\u00e3o inseridos novamente ap\u00f3s o seu consentimento quando visitar os nossos sites outra vez.<\/p><h2>9. Os seus direitos em rela\u00e7\u00e3o aos dados pessoais<\/h2><p>Tem os seguintes direitos em rela\u00e7\u00e3o aos seus dados pessoais:<\/p><ul>\n                    <li>confirma\u00e7\u00e3o da exist\u00eancia de processamento;<\/li>\n                    <li>acesso aos dados;<\/li>\n                    <li>corre\u00e7\u00e3o de dados incompletos, imprecisos ou desatualizados;<\/li>\n                    <li>anonimiza\u00e7\u00e3o, bloqueio ou exclus\u00e3o de dados desnecess\u00e1rios, excessivos ou processados em desacordo com as disposi\u00e7\u00f5es do Regulamento Geral de Prote\u00e7\u00e3o de Dados (RGPD);<\/li>\n                    <li>portabilidade dos dados para outro prestador de servi\u00e7os ou produtos, mediante pedido expresso, nos termos da regulamenta\u00e7\u00e3o da autoridade nacional, respeitando os segredos comerciais e industriais;<\/li>\n                    <li>elimina\u00e7\u00e3o dos dados pessoais tratados com o consentimento do titular, salvo nos casos previstos no art. 16 do Regulamento Geral de Prote\u00e7\u00e3o de Dados (RGPD);<\/li>\n                    <li>informa\u00e7\u00f5es sobre entidades p\u00fablicas e privadas com as quais o controlador partilhou dados;<\/li>\n                    <li>informa\u00e7\u00f5es sobre a possibilidade de n\u00e3o consentimento e sobre as consequ\u00eancias da nega\u00e7\u00e3o.<\/li>\n                <\/ul><p>Para exercer esses direitos, entre em contacto connosco. Consulte os detalhes de contacto no final desta Pol\u00edtica de Cookies. Se tiver uma reclama\u00e7\u00e3o sobre como lidamos com os seus dados, gostar\u00edamos de ouvi-la, mas tamb\u00e9m tem o direito de enviar uma reclama\u00e7\u00e3o \u00e0 Autoridade Nacional de Prote\u00e7\u00e3o de Dados (ANPD):<\/p><br \/>Autoridade Nacional de Prote\u00e7\u00e3o de Dados\n\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\t<br \/>Esplanada dos Minist\u00e9rios,\n\t\t\t\t\t\t<br \/>Bloco C,\n\t\t\t\t\t\t<br \/>2\u00ba andar,\n\t\t\t\t\t\t<br \/>CEP 70297-400 - Bras\u00edlia - DF.\n\t\t\t\t\t\t<br \/><a href=\"https:\/\/www.gov.br\/anpd\/pt-br\/canais_atendimento\/\" target=\"_blank\" rel=\"nofollow noopener\">S\u00edtio Web<\/a><h2>10. Detalhes de contacto<\/h2><p>Para perguntas e\/ou coment\u00e1rios sobre a nossa Pol\u00edtica de Cookies e esta declara\u00e7\u00e3o, entre em contacto connosco usando os seguintes detalhes de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">Grenade Technologies, Inc<\/span><br>\n                    <span class=\"cmplz-contact-address\">301-3450 Uptown Boulevard<br \/>\nVictoria BC V8Z 0B9<\/span><br>\n                    <span class=\"cmplz-contact-country\">Canad\u00e1<\/span><br>\n                    <span class=\"cmplz-contact-domain\">S\u00edtio Web: <a href=\"https:\/\/www.foosales.com\/pt\">https:\/\/www.foosales.com\/pt<\/a><\/span><br>\n                    <span class=\"cmplz-contact-email\">Correio eletr\u00f3nico: <span class=\"cmplz-obfuscate\">privacidade@<span class=\"cmplz-fmail-domain\">ex.com<\/span>foosales.com<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Esta Pol\u00edtica de Cookies foi sincronizada com <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\" rel=\"nofollow noopener\">cookiedatabase.org<\/a> em Julho 13, 2026.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":75,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-180612","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/pages\/180612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/comments?post=180612"}],"version-history":[{"count":1,"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/pages\/180612\/revisions"}],"predecessor-version":[{"id":182386,"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/pages\/180612\/revisions\/182386"}],"wp:attachment":[{"href":"https:\/\/www.foosales.com\/pt\/wp-json\/wp\/v2\/media?parent=180612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}